{"id":1609,"date":"2022-03-03T23:01:59","date_gmt":"2022-03-03T22:01:59","guid":{"rendered":"http:\/\/montse-herrera.com\/?p=1609"},"modified":"2023-10-10T15:13:28","modified_gmt":"2023-10-10T13:13:28","slug":"la-organizacion-inteligente-compromiso-con-el-crecimiento-y-el-aprendizaje","status":"publish","type":"post","link":"https:\/\/montse-herrera.com\/index.php\/2022\/03\/03\/la-organizacion-inteligente-compromiso-con-el-crecimiento-y-el-aprendizaje\/","title":{"rendered":"La organizaci\u00f3n inteligente: compromiso con el crecimiento y el aprendizaje"},"content":{"rendered":"<p>[et_pb_section fb_built=\u00bb1&#8243; _builder_version=\u00bb4.14.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_row _builder_version=\u00bb4.14.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_column type=\u00bb4_4&#8243; _builder_version=\u00bb4.14.8&#8243; _module_preset=\u00bbdefault\u00bb global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb][et_pb_text _builder_version=\u00bb4.14.8&#8243; _module_preset=\u00bbdefault\u00bb hover_enabled=\u00bb0&#8243; global_colors_info=\u00bb{}\u00bb theme_builder_area=\u00bbpost_content\u00bb sticky_enabled=\u00bb0&#8243;]<\/p>\n<p style=\"text-align: justify;\"><span>Las organizaciones s\u00f3lo pueden aprender a trav\u00e9s de las personas. El aprendizaje individual no garantiza el aprendizaje organizacional, pero no hay aprendizaje organizacional sin el individual.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Peter Senge, en su obra \u201cLa quinta disciplina\u201d, nos habla sobre el dominio personal como una de las disciplinas fundamentales de las organizaciones abiertas al aprendizaje. Este concepto de dominio personal hace referencia al crecimiento y aprendizaje personal: <\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><span>\u201c<em>La gente con alto nivel de dominio personal expande continuamente su aptitud para crear los resultados que buscan en la vida. De su b\u00fasqueda del aprendizaje continuo surge el esp\u00edritu de la organizaci\u00f3n inteligente\u201d.<\/em><\/span><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\"><span>En este contexto \u201caprendizaje\u201d, en t\u00e9rminos de Peter Senge, significa expandir la aptitud para producir los resultados que deseamos. Es necesario disponer de personas en todos los niveles con esta capacidad de aprendizaje, de esta manera se fomenta el desarrollo de organizaciones inteligentes.<\/span><\/p>\n<p style=\"text-align: justify;\"><span>Algunas de las caracter\u00edsticas de las personas con dominio personal:<\/span><\/p>\n<ul style=\"text-align: justify;\">\n<li><span>La visi\u00f3n es una vocaci\u00f3n no s\u00f3lo un ideal<\/span><\/li>\n<li><span>Perciben la realidad actual como aliado<\/span><\/li>\n<li><span>Aprovechan las fuerzas del cambio, no se resisten<\/span><\/li>\n<li><span>Inquisitivas, ven la realidad con precisi\u00f3n<\/span><\/li>\n<li><span>Se sienten conectadas con otras personas y con la vida misma<\/span><\/li>\n<li><span>No sacrifican su singularidad<\/span><\/li>\n<li><span>Se sienten parte de un proceso creativo m\u00e1s amplio en el que pueden influir<\/span><\/li>\n<li><span>Viven en continuo aprendizaje<\/span><\/li>\n<li><span>Son conscientes de sus l\u00edmites<\/span><\/li>\n<li><span>Disponen de un alto nivel de confianza<\/span><\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span>Las organizaciones abiertas al aprendizaje incentivan el crecimiento y aprendizaje. El desarrollo de personas no es un medio para conseguir los fines de la organizaci\u00f3n, sino que existe un compromiso incondicional con su bienestar y su felicidad, m\u00e1s all\u00e1 de un mero instrumento para conseguir sus objetivos.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span>\u00bfSobre qu\u00e9 principios se sustenta la disciplina del dominio personal?<\/span><\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong><span><\/span><\/strong><\/h5>\n<h5 style=\"text-align: justify;\"><strong><span>Visi\u00f3n personal<\/span><\/strong><\/h5>\n<p style=\"text-align: justify;\">El dominio personal requiere focalizarse continuamente en lo que uno desea, la visi\u00f3n debe ser intr\u00ednseca, debe nacer de dentro. Cuando las personas disponen de un inter\u00e9s genuino, se comprometen con naturalidad, energ\u00eda y entusiasmo. Nada ocurra hasta que no existe una visi\u00f3n, pero una visi\u00f3n sin prop\u00f3sito y sin vocaci\u00f3n s\u00f3lo es una buena idea.<\/p>\n<p style=\"text-align: justify;\"><strong><span><\/span><\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong><span>Sostener la tensi\u00f3n creativa<\/span><\/strong><\/h5>\n<p style=\"text-align: justify;\">La brecha que existe entre la realidad y nuestra visi\u00f3n es la tensi\u00f3n creativa, la fuerza que nos empuja a movernos hacia nuestra visi\u00f3n. Cuando e<span>sta brecha genera sentimientos de angustia, produce desaliento y como consecuencia tendemos a rebajar nuestra visi\u00f3n, pero en estos casos no se trata de tensi\u00f3n creativa sino de tensi\u00f3n emocional. Cuando comprendemos la tensi\u00f3n creativa es cuando obtenemos la energ\u00eda para el cambio. No importa lo que la visi\u00f3n es, sino lo que la visi\u00f3n logra. <\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span><\/span><\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong><span>Conflicto estructural<\/span><\/strong><\/h5>\n<p style=\"text-align: justify;\">Hace referencia a las creencias profundas dif\u00edciles de identificar que nos alejan de nuestra visi\u00f3n (\u201cno puedes\u201d, \u201cno lo mereces\u201d,\u2026) generando un conflicto estructural. El conflicto estructural s\u00f3lo se puede superar cambiando nuestras creencias a medida que acumulamos nuevas experiencias y desarrollamos el dominio personal.<\/p>\n<p style=\"text-align: justify;\"><strong><span><\/span><\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong><span>Compromiso con la verdad<\/span><\/strong><\/h5>\n<p style=\"text-align: justify;\"><span>Significa ensanchar nuestra percepci\u00f3n, cuestionar nuestras teor\u00edas. Es importante tomar conciencia de las estructuras que subyacen a los hechos y c\u00f3mo nuestros actos impactan en los resultados que obtenemos. Somos prisioneros de las estructuras de las que no somos conscientes, la consciencia nos da el poder para poder modificarlas.<\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span><\/span><\/strong><\/p>\n<h5 style=\"text-align: justify;\"><strong><span>Usando el subconsciente<\/span><\/strong><\/h5>\n<p style=\"text-align: justify;\">Hace referencia a la competencia inconsciente, es decir, aquellas tareas complejas que realizamos sin prestarles atenci\u00f3n. <span>Las personas con dominio personal se concentran en el resultado deseado. Es necesario separar lo que deseamos de lo que creemos necesitar para alcanzarlo; para ello ante una meta podemos plantearnos la siguiente pregunta: \u00bfSi lo consiguiera que me dar\u00eda? La respuesta normalmente revela deseos m\u00e1s profundos, de esta manera podemos distinguir entre metas intermedias y metas intr\u00ednsecas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span><\/span><\/p>\n<p style=\"text-align: justify;\"><strong><span>\u00bfC\u00f3mo puede una organizaci\u00f3n alentar el desarrollo de esta disciplina?<\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><span>El crecimiento personal y el aprendizaje continuo se deben desarrollar de manera voluntaria, se trata de una elecci\u00f3n. <\/span><\/p>\n<p style=\"text-align: justify;\"><span>Para fomentarlo es necesario generar un clima organizativo basado en los principios del dominio personal, <\/span><span>donde se genere el espacio adecuado para construir visiones, expresarlas y escuchar la visi\u00f3n de los dem\u00e1s, donde exista un compromiso con la verdad, la indagaci\u00f3n y se cuestione el status quo, d\u00f3nde se permita la posibilidad y se genere la voluntad de enfrentar las brechas provocadas entre nuestra visi\u00f3n y la realidad actual, facilitar el desarrollo de una perspectiva sist\u00e9mica, y sobretodo disponer de l\u00edderes que practiquen con el ejemplo, no hay nada m\u00e1s alentador para promover el dominio personal que la seriedad en la propia b\u00fasqueda. <\/span><\/p>\n<blockquote>\n<p style=\"text-align: justify;\"><span>\u201cEl verdadero aprendizaje llega al coraz\u00f3n de lo que significa ser humano. A trav\u00e9s del aprendizaje nos re-creamos a nosotros mismos, nos capacitamos para hacer algo que antes no pod\u00edamos, percibimos nuevamente el mundo y nuestra relaci\u00f3n con \u00e9l, ampliamos nuestra capacidad para crear, para formar parte del proceso generativo de la vida.\u201d Peter Senge.<\/span><\/p>\n<p style=\"text-align: justify;\"><span><\/span><\/p>\n<p style=\"text-align: justify;\"><a href=\"Imagen%20de &lt;a href=&quot;https:\/\/www.freepik.es\/foto-gratis\/concepto-dictadura-dibujo-bombilla_31502542.htm#query=collage%20vintage%20bombilla&amp;position=17&amp;from_view=search&amp;track=ais&quot;&gt;Freepik&lt;\/a&gt;\"><span>Imagen<\/span><\/a><\/p>\n<\/blockquote>\n<p style=\"text-align: justify;\">[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las organizaciones s\u00f3lo pueden aprender a trav\u00e9s de las personas. El aprendizaje individual no garantiza el aprendizaje organizacional, pero no hay aprendizaje organizacional sin el individual. Peter Senge, en su obra \u201cLa quinta disciplina\u201d, nos habla sobre el dominio personal como una de las disciplinas fundamentales de las organizaciones abiertas al aprendizaje. Este concepto de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1866,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"1081"},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/posts\/1609"}],"collection":[{"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/comments?post=1609"}],"version-history":[{"count":8,"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/posts\/1609\/revisions"}],"predecessor-version":[{"id":1915,"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/posts\/1609\/revisions\/1915"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/media\/1866"}],"wp:attachment":[{"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/media?parent=1609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/categories?post=1609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/montse-herrera.com\/index.php\/wp-json\/wp\/v2\/tags?post=1609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}